{"id":894,"date":"2025-09-10T13:31:22","date_gmt":"2025-09-10T11:31:22","guid":{"rendered":"https:\/\/holztrattner-schmid.de\/home\/cookie-richtlinie-eu\/"},"modified":"2025-09-10T13:31:22","modified_gmt":"2025-09-10T11:31:22","slug":"cookie-richtlinie-eu","status":"publish","type":"page","link":"https:\/\/holztrattner-schmid.de\/home\/cookie-richtlinie-eu\/","title":{"rendered":"Cookie-Richtlinie (EU)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Diese Cookie-Richtlinie wurde zuletzt am 10. September 2025 aktualisiert und gilt f\u00fcr B\u00fcrger und Einwohner mit st\u00e4ndigem Wohnsitz im Europ\u00e4ischen Wirtschaftsraum und der Schweiz.<\/i><br><\/p><h2>1. Einf\u00fchrung<\/h2><p>Unsere Website, <a href=\"https:\/\/holztrattner-schmid.de\/home\">https:\/\/holztrattner-schmid.de\/home<\/a> (im folgenden: &#8222;Die Website&#8220;) verwendet Cookies und \u00e4hnliche Technologien (der Einfachheit halber werden all diese unter &#8222;Cookies&#8220; zusammengefasst). Cookies werden au\u00dferdem von uns beauftragten Drittparteien platziert. In dem unten stehendem Dokument informieren wir dich \u00fcber die Verwendung von Cookies auf unserer Website.<\/p><h2>2. Was sind Cookies?<\/h2><p>Ein Cookie ist eine einfache kleine Datei, die gemeinsam mit den Seiten einer Internetadresse versendet und vom Webbrowser auf dem PC oder einem anderen Ger\u00e4t gespeichert werden kann. Die darin gespeicherten Informationen k\u00f6nnen w\u00e4hrend folgender Besuche zu unseren oder den Servern relevanter Drittanbieter gesendet werden.<\/p><h2>3. Was sind Skripte?<\/h2><p>Ein Script ist ein St\u00fcck Programmcode, das benutzt wird, um unserer Website Funktionalit\u00e4t und Interaktivit\u00e4t zu erm\u00f6glichen. Dieser Code wird auf unseren Servern oder auf deinem Ger\u00e4t ausgef\u00fchrt.<\/p><h2>4. Was ist ein Web Beacon?<\/h2><p>Ein Web-Beacon (auch Pixel-Tag genannt), ist ein kleines unsichtbares Textfragment oder Bild auf einer Website, das benutzt wird, um den Verkehr auf der Website zu \u00fcberwachen. Um dies zu erm\u00f6glichen werden diverse Daten von dir mittels Web-Beacons gespeichert.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Technische oder funktionelle Cookies<\/p><p>Einige Cookies stellen sicher, dass bestimmte Teile der Website ordnungsgem\u00e4\u00df funktionieren und deine Benutzereinstellungen weiterhin in Erinnerung bleiben. Durch das Setzen funktionaler Cookies erleichtern wir dir den Besuch unserer Website. Auf diese Weise musst du beim Besuch unserer Website nicht wiederholt dieselben Informationen eingeben, so bleiben Artikel beispielsweise in deinem Warenkorb, bis du bezahlst. Wir k\u00f6nnen diese Cookies ohne deine Einwilligung platzieren.<\/p><p class=\"cmplz-subtitle\">5.2 Marketing- \/ Tracking-Cookies<\/p><p>Marketing- \/ Tracking-Cookies sind Cookies oder eine andere Form der lokalen Speicherung, die zur Erstellung von Benutzerprofilen verwendet werden, um Werbung anzuzeigen oder den Benutzer auf dieser Website oder \u00fcber mehrere Websites hinweg f\u00fcr \u00e4hnliche Marketingzwecke zu verfolgen.<\/p><h2>6. Platzierte Cookies<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funktional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden WordPress f\u00fcr Website-Entwicklung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Browser-Angaben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speicher die Benutzervorlieben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speicher die Benutzervorlieben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Benutzer eingeloggt lassen<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">\u00fcberpr\u00fcft, ob Cookies gesetzt werden k\u00f6nnen<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Fonts f\u00fcr Anzeige von Webfonts. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Maps f\u00fcr Kartenanzeige. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">Mehr lesen<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Maps Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sonstiges<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_sonstiges\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sonstiges<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sonstiges\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sonstiges\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Die Weitergabe von Daten wird noch untersucht<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_jwp<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">pxcelPage_c01008<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">pxcelPage_c01002<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cookieyes-consent<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_jpw<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Einwilligung<\/h2><p>Wenn du unsere Website das erste Mal besuchst, zeigen wir dir ein Pop-Up mit einer Erkl\u00e4rung \u00fcber Cookies. Sobald du auf \u201eEinstellungen speichern\u201c klickst, gibst du uns deine Einwilligung alle von dir gew\u00e4hlten Kategorien von Cookies und Plugins wie in dieser Cookie-Erkl\u00e4rung beschrieben zu verwenden. Du kannst die Verwendung von Cookies \u00fcber deinen Browser deaktivieren, aber bitte beachte, dass unsere Website dann unter Umst\u00e4nden nicht richtig funktioniert.<\/p><p class=\"cmplz-subtitle\">7.1 Verwalte deine Einwilligungseinstellungen<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Du hast die Cookie-Richtlinie ohne Javascript-Unterst\u00fctzung geladen.&nbsp;Unter AMP kannst du den Button zum Zustimmen der Einwilligung unten auf der Seite verwenden.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Aktivierung\/Deaktivierung und L\u00f6schen von Cookies<\/h2><p>Du kannst deinen Internetbrowser verwenden um automatisch oder manuell Cookies zu l\u00f6schen. Du kannst au\u00dferdem spezifizieren ob spezielle Cookies nicht platziert werden sollen. Eine andere M\u00f6glichkeit ist es deinen  Internetbrowser derart einzurichten, dass du jedes Mal benachrichtigt wirst, wenn ein Cookie platziert wird. F\u00fcr weitere Information \u00fcber diese M\u00f6glichkeiten beachte die Anweisungen in der Hilfesektion deines Browsers.<\/p><p>Bitte nimm zur Kenntnis, dass unsere Website m\u00f6glicherweise nicht richtig funktioniert, wenn alle Cookies deaktiviert sind. Wenn du die Cookies in deinem Browser l\u00f6scht, werden diese neu platziert, wenn du unsere Website erneut besuchst.<\/p><h2>9. Deine Rechte in Bezug auf personenbezogene Daten<\/h2><p>Du hast folgende Rechte in Bezug auf deine personenbezogenen Daten:<\/p><ul>\n                    <li>Du hast das Recht zu erfahren, warum deine personenbezogenen Daten ben\u00f6tigt werden, was damit passiert und wie lange sie aufbewahrt werden.<\/li>\n                    <li>Auskunftsrecht: Du hast das Recht deine uns bekannten pers\u00f6nliche Daten einzusehen.\n\t<\/li>\n                    <li>Recht auf Berichtigung: Du hast das Recht wann immer du w\u00fcnscht, deine personenbezogenen Daten zu erg\u00e4nzen, zu korrigieren sowie gel\u00f6scht oder blockiert zu bekommen.<\/li>\n                    <li>Wenn du uns deine Einwilligung zur Verarbeitung deiner Daten erteilst, hast du das Recht diese Einwilligung zu widerrufen und deine personenbezogenen Daten l\u00f6schen zu lassen.<\/li>\n                    <li>Recht auf Daten\u00fcbertragbarkeit: Du hast das Recht, alle deine personenbezogenen Daten von dem f\u00fcr die Verarbeitung Verantwortlichen anzufordern und sie vollst\u00e4ndig an einen anderen f\u00fcr die Verarbeitung Verantwortlichen zu \u00fcbermitteln.<\/li>\n                    <li>Widerspruchsrecht: Du kannst der Verarbeitung deiner Daten widersprechen. Wir entsprechen dem, es sei denn es gibt berechtigte Gr\u00fcnde f\u00fcr die Verarbeitung.<\/li>\n                <\/ul><p>Um diese Rechte auszu\u00fcben kontaktiere uns bitte. Bitte beziehe dich auf die Kontaktdaten am Ende dieser Cookie-Erkl\u00e4rung. Wenn du eine Beschwerde dar\u00fcber hast, wie wir deine Daten behandeln, w\u00fcrden wir diese gerne h\u00f6ren, aber du hast auch das Recht diese an die Aufsichtsbeh\u00f6rde (Datenschutzbeh\u00f6rde) zu richten.<\/p><h2>10. Kontaktdaten<\/h2><p>F\u00fcr Fragen und\/oder Kommentare \u00fcber unsere Cookie-Richtlinien und diese Aussage kontaktiere uns bitte mittels der folgenden Kontaktdaten:<\/p><p><span class=\"cmplz-contact-organisation\">Holztrattner \/ Schmid Anwaltskanzlei<\/span><br>\n                      <span class=\"cmplz-contact-address\">Otto-Wagner-Stra\u00dfe 2, 82110 Germering<\/span><br>\n                      <span class=\"cmplz-contact-country\">Deutschland<\/span><br>\n                    Website: <span class=\"cmplz-contact-domain\"><a href=\"https:\/\/holztrattner-schmid.de\/home\">https:\/\/holztrattner-schmid.de\/home<\/a><\/span><br>\n                    E-Mail: <span class=\"cmplz-contact-email\"><span class=\"cmplz-obfuscate\">&#107;&#097;&#110;zlei@<span class=\"cmplz-fmail-domain\">&#101;&#120;.c&#111;m<\/span>ho&#108;zt&#114;&#097;&#116;&#116;&#110;e&#114;&#045;s&#099;&#104;m&#105;d.de<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Diese Cookie-Richtlinie wurde mit <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> am 21. April 2026 synchronisiert.<\/p><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-894","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/pages\/894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/comments?post=894"}],"version-history":[{"count":0,"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/pages\/894\/revisions"}],"wp:attachment":[{"href":"https:\/\/holztrattner-schmid.de\/home\/wp-json\/wp\/v2\/media?parent=894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}